{"id":2705,"date":"2019-11-15T19:43:35","date_gmt":"2019-11-15T18:43:35","guid":{"rendered":"https:\/\/therentalstudios.it\/?page_id=2705"},"modified":"2026-02-05T14:53:55","modified_gmt":"2026-02-05T13:53:55","slug":"chi-siamo","status":"publish","type":"page","link":"https:\/\/therentalstudios.it\/en\/chi-siamo\/","title":{"rendered":"ABOUT US"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2705\" class=\"elementor elementor-2705\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-97f18de elementor-section-stretched elementor-section-full_width elementor-section-height-min-height elementor-section-content-middle elementor-section-height-default elementor-section-items-middle\" data-id=\"97f18de\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3f8ee51\" data-id=\"3f8ee51\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8570435 elementor-widget elementor-widget-heading\" data-id=\"8570435\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-xxl\">CHI SIAMO<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ee86ca2 elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"3ee86ca2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3fcf36b0\" data-id=\"3fcf36b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4bfdcf4a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4bfdcf4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41aa1ae9 elementor-widget elementor-widget-heading\" data-id=\"41aa1ae9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-large\">IL CARATTERE DI UNA CASA, IL COMFORT DI UN HOTEL\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-497a9f93 elementor-widget elementor-widget-text-editor\" data-id=\"497a9f93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The Rental Studios \u00e8 una societ\u00e0 con un\u2019esperienza decennale nel settore dell\u2019affitto di appartamenti per <strong>periodi<\/strong> sia <strong>brevi<\/strong>\u00a0sia\u00a0<strong>lunghi.<\/strong> Offriamo diverse soluzioni abitative dal <a href=\"https:\/\/therentalstudios.it\/monolocali\/\"><span style=\"text-decoration: underline;\">monolocale<\/span><\/a> al <a href=\"https:\/\/therentalstudios.it\/trilocali\/\"><span style=\"text-decoration: underline;\">trilocale<\/span><\/a> ognuno accuratamente arredato e corredato per garantire ai nostri ospiti un soggiorno di qualit\u00e0.<\/p><p>Le nostre soluzioni abitative sono perfette anche per le <strong>aziende<\/strong> che hanno la necessit\u00e0 di ospitare parte del loro personale nella citt\u00e0 di Milano.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f03dc8a\" data-id=\"f03dc8a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-507ecf86 elementor-widget elementor-widget-image\" data-id=\"507ecf86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/therentalstudios.it\/wp-content\/uploads\/2020\/01\/resort-1.png\" class=\"attachment-full size-full wp-image-4066\" alt=\"\" srcset=\"https:\/\/therentalstudios.it\/wp-content\/uploads\/2020\/01\/resort-1.png 512w, https:\/\/therentalstudios.it\/wp-content\/uploads\/2020\/01\/resort-1-320x320.png 320w, https:\/\/therentalstudios.it\/wp-content\/uploads\/2020\/01\/resort-1-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-26bd2fa3 elementor-section-height-min-height elementor-section-content-middle elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"26bd2fa3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-78df1c67\" data-id=\"78df1c67\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b0611c7 elementor-widget elementor-widget-image\" data-id=\"5b0611c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/therentalstudios.it\/wp-content\/uploads\/elementor\/thumbs\/address-olgn606ydori01hb8jzo9a24l52fv17gxv0k1t4tbw.png\" title=\"address rental\" alt=\"address rental\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4ab43d0d\" data-id=\"4ab43d0d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15b979bb elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"15b979bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-602540a1 elementor-widget elementor-widget-heading\" data-id=\"602540a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-large\">ZONE STRATEGICHE<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5606e130 elementor-widget elementor-widget-text-editor\" data-id=\"5606e130\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Rental Studio offre studios nelle zone pi\u00f9 strategiche di Milano: vicinanza a centri direzionali, poli universitari, metropolitane, zone di lusso, zone di business e zone di divertimento.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1bc316fe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1bc316fe\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-39f9ab99\" data-id=\"39f9ab99\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e5772a1 elementor-widget elementor-widget-menu-anchor\" data-id=\"e5772a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"servizi\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6853608 elementor-widget elementor-widget-heading\" data-id=\"6853608\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-large\">SERVIZI INCLUSI\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1040dc21 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1040dc21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-431f8758 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"431f8758\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6d68c322\" data-id=\"6d68c322\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d12d217 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"d12d217\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/therentalstudios.it\/wp-content\/uploads\/2020\/01\/maintenance.png\" class=\"attachment-full size-full wp-image-3393\" alt=\"maintenance\" srcset=\"https:\/\/therentalstudios.it\/wp-content\/uploads\/2020\/01\/maintenance.png 512w, https:\/\/therentalstudios.it\/wp-content\/uploads\/2020\/01\/maintenance-150x150.png 150w, https:\/\/therentalstudios.it\/wp-content\/uploads\/2020\/01\/maintenance-320x320.png 320w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">PRONTO INTERVENTO PER EVENTUALI GUASTI<\/h3><p class=\"elementor-image-box-description\">Il nostro personale e\u0300 sempre pronto per qualsiasi tipo di evenienza che riguardi riparazioni, sostituzioni o piccoli interventi di manutenzione ordinaria e straordinaria. <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24094937 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"24094937\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/therentalstudios.it\/wp-content\/uploads\/2020\/01\/vacuum.png\" class=\"attachment-full size-full wp-image-3072\" alt=\"PULIZIE\" srcset=\"https:\/\/therentalstudios.it\/wp-content\/uploads\/2020\/01\/vacuum.png 512w, https:\/\/therentalstudios.it\/wp-content\/uploads\/2020\/01\/vacuum-150x150.png 150w, https:\/\/therentalstudios.it\/wp-content\/uploads\/2020\/01\/vacuum-320x320.png 320w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">PULIZIE*<\/h3><p class=\"elementor-image-box-description\">Il  personale qualificato e di fiducia effettua la pulizia contestualmente al cambio della biancheria da bagno, da letto e da cucina fornita da noi.<br><br><br><br><\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37add3cd elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"37add3cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/therentalstudios.it\/wp-content\/uploads\/2020\/01\/customer-1.png\" class=\"attachment-full size-full wp-image-3405\" alt=\"customer rental\" srcset=\"https:\/\/therentalstudios.it\/wp-content\/uploads\/2020\/01\/customer-1.png 512w, https:\/\/therentalstudios.it\/wp-content\/uploads\/2020\/01\/customer-1-150x150.png 150w, https:\/\/therentalstudios.it\/wp-content\/uploads\/2020\/01\/customer-1-320x320.png 320w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"> FLESSIBILITA\u2019 TEMPORALE<\/h3><p class=\"elementor-image-box-description\">Le prenotazioni, sempre rinnovabili se lo studios \u00e8 disponibile, potranno coprire archi temporali brevi, come pochi giorni, oppure pi\u00f9 lunghi, fino a un anno. Il preavviso per il rilascio anticipato dello studio sar\u00e0 di 60 giorni, senza penali.\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-26ced456\" data-id=\"26ced456\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c827de8 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"c827de8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/therentalstudios.it\/wp-content\/uploads\/2020\/01\/air-conditioning.png\" class=\"attachment-full size-full wp-image-3394\" alt=\"air-conditioning\" srcset=\"https:\/\/therentalstudios.it\/wp-content\/uploads\/2020\/01\/air-conditioning.png 512w, https:\/\/therentalstudios.it\/wp-content\/uploads\/2020\/01\/air-conditioning-150x150.png 150w, https:\/\/therentalstudios.it\/wp-content\/uploads\/2020\/01\/air-conditioning-320x320.png 320w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">ARIA CONDIZIONATA  RISCALDAMENTO*<\/h3><p class=\"elementor-image-box-description\">Aria condizionata abbinata a pompa di calore rendono il clima dello studios perfetto tutto l\u2019anno. Ogni studios e\u0300 dotato di proprio contatore per facilitare il controllo del consumo di energia. <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1181f806 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"1181f806\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/therentalstudios.it\/wp-content\/uploads\/2019\/12\/102649.png\" class=\"attachment-full size-full wp-image-2911\" alt=\"sicurezza\" srcset=\"https:\/\/therentalstudios.it\/wp-content\/uploads\/2019\/12\/102649.png 512w, https:\/\/therentalstudios.it\/wp-content\/uploads\/2019\/12\/102649-150x150.png 150w, https:\/\/therentalstudios.it\/wp-content\/uploads\/2019\/12\/102649-320x320.png 320w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">SICUREZZA <\/h3><p class=\"elementor-image-box-description\">Tutti i nostri studios sono dotati di porta blindata, videocitofono, estintore e rilevatore di gas. In alcuni edifici \u00e8 inoltre attivo un servizio di videosorveglianza 24 ore su 24.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f76977e elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"1f76977e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/therentalstudios.it\/wp-content\/uploads\/2020\/01\/ironing-1.png\" class=\"attachment-full size-full wp-image-3403\" alt=\"ironing\" srcset=\"https:\/\/therentalstudios.it\/wp-content\/uploads\/2020\/01\/ironing-1.png 512w, https:\/\/therentalstudios.it\/wp-content\/uploads\/2020\/01\/ironing-1-150x150.png 150w, https:\/\/therentalstudios.it\/wp-content\/uploads\/2020\/01\/ironing-1-320x320.png 320w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">SERVIZIO LAVANDERIA*<\/h3><p class=\"elementor-image-box-description\">Alcuni residence sono dotati del servizio lavanderia  veloce e sicuro. Basta lasciare i propri indumenti all\u2019interno dell\u2019apposita sacca; la governante lavera\u0300, stirera\u0300 e riconsegnera\u0300 direttamente negli studios i vostri vestiti. <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-6068572 elementor-widget elementor-widget-text-editor\" data-id=\"6068572\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>* per questi servizi trovate all\u2019interno dello STUDIOS i relativi costi<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2b828cbf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b828cbf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-af8204f\" data-id=\"af8204f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33cfab1 elementor-widget elementor-widget-heading\" data-id=\"33cfab1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">RICHIEDI INFORMAZIONI<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c903ba elementor-button-align-center elementor-widget elementor-widget-form\" data-id=\"7c903ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Pagina chi siamo \" aria-label=\"Pagina chi siamo \">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"2705\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"7c903ba\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"THE RENTAL STUDIOS\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nome\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_1 elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_1\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tCognome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_1]\" id=\"form-field-field_1\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Cognome\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-field_2 elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_2\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tTelefono\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[field_2]\" id=\"form-field-field_2\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Telefono\" required=\"required\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tMessaggio\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Messaggio\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-field_3 elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[field_3]\" id=\"form-field-field_3\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\" required=\"required\">\n\t\t\t\t<label for=\"form-field-field_3\">I tuoi dati personali saranno utilizzati per elaborare la tua richiesta e per altri scopi descritti nella nostra informativa sulla privacy. <\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">INVIA<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>CHI SIAMO IL CARATTERE DI UNA CASA, IL COMFORT DI UN HOTEL The Rental Studios \u00e8 una societ\u00e0 con un\u2019esperienza decennale nel settore dell\u2019affitto di appartamenti per periodi sia brevi\u00a0sia\u00a0lunghi. Offriamo diverse soluzioni abitative dal monolocale al trilocale ognuno accuratamente arredato e corredato per garantire ai nostri ospiti un soggiorno di qualit\u00e0. Le nostre soluzioni [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4114,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-2705","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Affitti per brevi periodi per aziende e privati | The Rental Studios<\/title>\n<meta name=\"description\" content=\"The Rental Studios \u00e8 una societ\u00e0 milanese che opera nell&#039;ambito degli affitti a breve e medio periodo per aziende e privati. Cerca sul sito la soluzione per te!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/therentalstudios.it\/en\/chi-siamo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Affitti per brevi periodi per aziende e privati | The Rental Studios\" \/>\n<meta property=\"og:description\" content=\"The Rental Studios \u00e8 una societ\u00e0 milanese che opera nell&#039;ambito degli affitti a breve e medio periodo per aziende e privati. Cerca sul sito la soluzione per te!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/therentalstudios.it\/en\/chi-siamo\/\" \/>\n<meta property=\"og:site_name\" content=\"THE RENTAL STUDIOS\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-05T13:53:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/therentalstudios.it\/wp-content\/uploads\/2020\/02\/cover-chi-siamo-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"691\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/therentalstudios.it\\\/chi-siamo\\\/\",\"url\":\"https:\\\/\\\/therentalstudios.it\\\/chi-siamo\\\/\",\"name\":\"Affitti per brevi periodi per aziende e privati | The Rental Studios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/therentalstudios.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/therentalstudios.it\\\/chi-siamo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/therentalstudios.it\\\/chi-siamo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/therentalstudios.it\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/cover-chi-siamo-scaled.jpg\",\"datePublished\":\"2019-11-15T18:43:35+00:00\",\"dateModified\":\"2026-02-05T13:53:55+00:00\",\"description\":\"The Rental Studios \u00e8 una societ\u00e0 milanese che opera nell'ambito degli affitti a breve e medio periodo per aziende e privati. Cerca sul sito la soluzione per te!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/therentalstudios.it\\\/chi-siamo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/therentalstudios.it\\\/chi-siamo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/therentalstudios.it\\\/chi-siamo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/therentalstudios.it\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/cover-chi-siamo-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/therentalstudios.it\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/cover-chi-siamo-scaled.jpg\",\"width\":2560,\"height\":691,\"caption\":\"cover chi siamo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/therentalstudios.it\\\/chi-siamo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/therentalstudios.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CHI SIAMO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/therentalstudios.it\\\/#website\",\"url\":\"https:\\\/\\\/therentalstudios.it\\\/\",\"name\":\"The Rental Studios\",\"description\":\"Serviced Apartments\",\"publisher\":{\"@id\":\"https:\\\/\\\/therentalstudios.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/therentalstudios.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/therentalstudios.it\\\/#organization\",\"name\":\"The Rental Studios\",\"alternateName\":\"Serviced Apartment\",\"url\":\"https:\\\/\\\/therentalstudios.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/therentalstudios.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/therentalstudios.it\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-logo-the-rental-studio-1.jpg\",\"contentUrl\":\"https:\\\/\\\/therentalstudios.it\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-logo-the-rental-studio-1.jpg\",\"width\":512,\"height\":512,\"caption\":\"The Rental Studios\"},\"image\":{\"@id\":\"https:\\\/\\\/therentalstudios.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Affitti per brevi periodi per aziende e privati | The Rental Studios","description":"The Rental Studios \u00e8 una societ\u00e0 milanese che opera nell'ambito degli affitti a breve e medio periodo per aziende e privati. Cerca sul sito la soluzione per te!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/therentalstudios.it\/en\/chi-siamo\/","og_locale":"en_US","og_type":"article","og_title":"Affitti per brevi periodi per aziende e privati | The Rental Studios","og_description":"The Rental Studios \u00e8 una societ\u00e0 milanese che opera nell'ambito degli affitti a breve e medio periodo per aziende e privati. Cerca sul sito la soluzione per te!","og_url":"https:\/\/therentalstudios.it\/en\/chi-siamo\/","og_site_name":"THE RENTAL STUDIOS","article_modified_time":"2026-02-05T13:53:55+00:00","og_image":[{"width":2560,"height":691,"url":"https:\/\/therentalstudios.it\/wp-content\/uploads\/2020\/02\/cover-chi-siamo-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/therentalstudios.it\/chi-siamo\/","url":"https:\/\/therentalstudios.it\/chi-siamo\/","name":"Affitti per brevi periodi per aziende e privati | The Rental Studios","isPartOf":{"@id":"https:\/\/therentalstudios.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/therentalstudios.it\/chi-siamo\/#primaryimage"},"image":{"@id":"https:\/\/therentalstudios.it\/chi-siamo\/#primaryimage"},"thumbnailUrl":"https:\/\/therentalstudios.it\/wp-content\/uploads\/2020\/02\/cover-chi-siamo-scaled.jpg","datePublished":"2019-11-15T18:43:35+00:00","dateModified":"2026-02-05T13:53:55+00:00","description":"The Rental Studios \u00e8 una societ\u00e0 milanese che opera nell'ambito degli affitti a breve e medio periodo per aziende e privati. Cerca sul sito la soluzione per te!","breadcrumb":{"@id":"https:\/\/therentalstudios.it\/chi-siamo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/therentalstudios.it\/chi-siamo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/therentalstudios.it\/chi-siamo\/#primaryimage","url":"https:\/\/therentalstudios.it\/wp-content\/uploads\/2020\/02\/cover-chi-siamo-scaled.jpg","contentUrl":"https:\/\/therentalstudios.it\/wp-content\/uploads\/2020\/02\/cover-chi-siamo-scaled.jpg","width":2560,"height":691,"caption":"cover chi siamo"},{"@type":"BreadcrumbList","@id":"https:\/\/therentalstudios.it\/chi-siamo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/therentalstudios.it\/"},{"@type":"ListItem","position":2,"name":"CHI SIAMO"}]},{"@type":"WebSite","@id":"https:\/\/therentalstudios.it\/#website","url":"https:\/\/therentalstudios.it\/","name":"The Rental Studios","description":"Serviced Apartments","publisher":{"@id":"https:\/\/therentalstudios.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/therentalstudios.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/therentalstudios.it\/#organization","name":"The Rental Studios","alternateName":"Serviced Apartment","url":"https:\/\/therentalstudios.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/therentalstudios.it\/#\/schema\/logo\/image\/","url":"https:\/\/therentalstudios.it\/wp-content\/uploads\/2024\/03\/cropped-logo-the-rental-studio-1.jpg","contentUrl":"https:\/\/therentalstudios.it\/wp-content\/uploads\/2024\/03\/cropped-logo-the-rental-studio-1.jpg","width":512,"height":512,"caption":"The Rental Studios"},"image":{"@id":"https:\/\/therentalstudios.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/therentalstudios.it\/en\/wp-json\/wp\/v2\/pages\/2705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/therentalstudios.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/therentalstudios.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/therentalstudios.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/therentalstudios.it\/en\/wp-json\/wp\/v2\/comments?post=2705"}],"version-history":[{"count":89,"href":"https:\/\/therentalstudios.it\/en\/wp-json\/wp\/v2\/pages\/2705\/revisions"}],"predecessor-version":[{"id":10221,"href":"https:\/\/therentalstudios.it\/en\/wp-json\/wp\/v2\/pages\/2705\/revisions\/10221"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/therentalstudios.it\/en\/wp-json\/wp\/v2\/media\/4114"}],"wp:attachment":[{"href":"https:\/\/therentalstudios.it\/en\/wp-json\/wp\/v2\/media?parent=2705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}